{"id":1143,"date":"2013-06-20T14:30:18","date_gmt":"2013-06-20T14:30:18","guid":{"rendered":"http:\/\/kasperskydaily.com\/france\/?p=1143"},"modified":"2021-06-18T12:44:10","modified_gmt":"2021-06-18T10:44:10","slug":"5-plugins-firefox-qui-vous-permettront-de-renforcer-votre-confidentialite","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/5-plugins-firefox-qui-vous-permettront-de-renforcer-votre-confidentialite\/1143\/","title":{"rendered":"5 plugins Firefox qui vous permettront de renforcer votre confidentialit\u00e9"},"content":{"rendered":"<p>Il est de plus en plus difficile d\u2019assurer la confidentialit\u00e9 de vos informations lorsque vous naviguez sur Internet. Heureusement, il existe tout un march\u00e9 d\u2019extensions utilitaires, plus connues sous le nom de plugins et qui ont pour but de prot\u00e9ger votre navigation sur le Web, et ce quelque soit le navigateur que vous avez choisi. Chacun d\u2019entre eux propose un large choix d\u2019options; en ce qui concerne Firefox, voici un top 5 des meilleures extensions permettant d\u2019assurer la s\u00e9curit\u00e9 de vos informations.<\/p>\n<p><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06103733\/firefox_title_fr.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1145\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06103733\/firefox_title_fr.png\" alt=\"firefox_title_fr\" width=\"640\" height=\"420\"><\/a><\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093240\/logo_NoScript.png\" alt=\"\" width=\"64\" height=\"64\">NoScript\u00a0:<\/b> Les scripts qui fonctionnent en arri\u00e8re-plan sur les sites Internet sont l\u2019une des m\u00e9thodes les plus utilis\u00e9es par les pirates qui veulent exploiter les sites et les syst\u00e8mes des utilisateurs. <a href=\"https:\/\/addons.mozilla.org\/en-us\/firefox\/addon\/noscript\/\" target=\"_blank\" rel=\"noopener nofollow\">NoScript<\/a> \u00e9limine ce probl\u00e8me en permettant \u00e0 Javascript, \u00e0 Java et \u00e0 certains autres contenus ex\u00e9cutables de fonctionner uniquement sur des sites jug\u00e9s dignes de confiance par l\u2019utilisateur, il permet \u00e9galement de bloquer les exploits en conservant toutes les fonctionnalit\u00e9s du site.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093240\/2013-06-18-12_41_04-NoScript.png\" alt=\"\" width=\"504\" height=\"385\"><\/p>\n<p><b><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06103731\/Better_privacy.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-1146\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06103731\/Better_privacy.png\" alt=\"Better_privacy\" width=\"80\" height=\"80\"><\/a>Better Privacy :<\/b> Pour le meilleur, et bien trop souvent, pour le pire, les cookies permettent de pister nos mouvements sur Internet. Ils nous permettent de ne pas avoir \u00e0 nous connecter de nouveau \u00e0 chaque fois que nous visitons un site dot\u00e9 d\u2019un syst\u00e8me d\u2019authentification, ces derniers emmagasinent et envoient \u00e9galement des informations sur nos habitudes de navigation. <a href=\"https:\/\/addons.mozilla.org\/en-US\/firefox\/addon\/betterprivacy\/\" target=\"_blank\" rel=\"noopener nofollow\">Better Privacy <\/a>vous prot\u00e8ge contre une nouvelle esp\u00e8ce de cookies permanents que les entreprises de marketing utilisent pour inonder les utilisateurs de publicit\u00e9s. Sa protection consiste \u00e0 cr\u00e9er des listes de cookies Flash et permet aux utilisateurs de r\u00e9pertorier et de g\u00e9rer les cookies qu\u2019ils souhaitent autoriser ou non.<\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093239\/pure2013.png\" alt=\"\" width=\"43\" height=\"67\">Kaspersky\u00a0Anti-Banner : <\/b>Cette fonctionnalit\u00e9 est int\u00e9gr\u00e9e \u00e0 <a href=\"https:\/\/www.kaspersky.com\/fr\/internet-security\" target=\"_blank\" rel=\"noopener nofollow\">Kaspersky Internet Security 2013<\/a>, une plateforme qui prot\u00e8ge votre syst\u00e8me des menaces Internet, ainsi qu\u2019\u00e0 la suite anti-virus <a href=\"https:\/\/www.kaspersky.com\/fr\/pure\" target=\"_blank\" rel=\"noopener nofollow\">Kaspersky PURE 3.0<\/a>. L\u2019extension Kaspersky Anti-Banner bloque les contenus publicitaires situ\u00e9s dans les banni\u00e8res ainsi que ceux int\u00e9gr\u00e9s dans les interfaces de certains programmes disponibles en ligne. Une alternative ind\u00e9pendante \u00e0 Adblock Plus qui, tout comme l\u2019extension de Kaspersky Lab, \u00e9limine les publicit\u00e9s en ligne et bloque les domaines connus pour \u00eatre malveillants.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093239\/Pure_AntiBanner.png\" alt=\"\" width=\"569\" height=\"456\"><\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093239\/logo_SelfDestructCookies.png\" alt=\"\" width=\"64\" height=\"64\">Self-destructing Cookies\u00a0: <\/b>Tout comme Better Privacy, <a href=\"https:\/\/addons.mozilla.org\/en-us\/firefox\/addon\/self-destructing-cookies\/\" target=\"_blank\" rel=\"noopener nofollow\">Self-Destructing Cookies <\/a>a pour but d\u2019\u00e9liminer le pistage excessif des cookies. Pour cela, il d\u00e9sinstalle automatiquement les cookies lorsque ces derniers ne sont plus utilis\u00e9s par les onglets de navigation ouverts et les cookies de pistage sont automatiquement d\u00e9sinstall\u00e9s une fois d\u00e9tect\u00e9s. Il a \u00e9galement \u00e9t\u00e9 con\u00e7u pour fonctionner avec les listes d\u2019autorisation de permissions que procurent d\u2019autres extensions comme Ghostery et Adblock Plus.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093238\/SelfDestructCookies.png\" alt=\"\" width=\"454\" height=\"525\"><\/p>\n<p><b><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093238\/logo_Stealthy.png\" alt=\"\" width=\"64\" height=\"64\">Stealthy\u00a0:<\/b> Particuli\u00e8rement utile dans les pays o\u00f9 l\u2019acc\u00e8s aux r\u00e9seaux sociaux les plus populaires comme Facebook ou Youtube est bloqu\u00e9, cette extension cache votre adresse IP, vous pr\u00e9servant ainsi du pistage en ligne et vous permettant d\u2019\u00e9viter la censure exerc\u00e9e par les pare-feux. M\u00eame si la censure ne vous concerne pas, les proxies que\u00a0<a href=\"https:\/\/addons.mozilla.org\/en-us\/firefox\/addon\/stealthy\/\" target=\"_blank\" rel=\"noopener nofollow\">Stealthy<\/a> vous offre, vous permettent de surfer anonymement sur le Web, ce qui n\u2019est jamais une mauvaise chose.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/06\/06093238\/Stealthy.png\" alt=\"\" width=\"538\" height=\"428\"><\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il est de plus en plus difficile d\u2019assurer la confidentialit\u00e9 de vos informations lorsque vous naviguez sur Internet. Heureusement, il existe tout un march\u00e9 d\u2019extensions utilitaires, plus connues sous le<\/p>\n","protected":false},"author":41,"featured_media":1144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[180,113,345],"class_list":{"0":"post-1143","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-confidentialite","9":"tag-plugins","10":"tag-securite-de-navigation"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/5-plugins-firefox-qui-vous-permettront-de-renforcer-votre-confidentialite\/1143\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/confidentialite\/","name":"confidentialit\u00e9"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/1143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=1143"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/1143\/revisions"}],"predecessor-version":[{"id":17182,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/1143\/revisions\/17182"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=1143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=1143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=1143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}