{"id":17430,"date":"2021-08-06T15:20:27","date_gmt":"2021-08-06T13:20:27","guid":{"rendered":"https:\/\/www.kaspersky.fr\/blog\/?p=17430"},"modified":"2022-05-05T13:44:14","modified_gmt":"2022-05-05T11:44:14","slug":"owncloud-scanengine-integration","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/owncloud-scanengine-integration\/17430\/","title":{"rendered":"Les fichiers stock\u00e9s sur le Cloud de l&rsquo;entreprise sont-ils naturellement sans danger ?"},"content":{"rendered":"<p>Il n\u2019y a presque aucune entreprise de nos jours qui n\u2019utilise pas d\u2019environnement Cloud pour stocker et partager des donn\u00e9es. Si ce n\u2019\u00e9tait pas le cas, les entreprises actuelles n\u2019existeraient plus. Apr\u00e8s la pand\u00e9mie mondiale de 2020, de nombreuses entreprises ont \u00e9t\u00e9 t\u00e9moins ou ont elles-m\u00eames v\u00e9cu le remplacement du travail en pr\u00e9sentiel par le t\u00e9l\u00e9travail. Ce changement s\u2019\u00e9tant av\u00e9r\u00e9 efficace, elles ne sont pas press\u00e9es de refaire travailler leurs employ\u00e9s en pr\u00e9sentiel. D\u2019autre part, les employ\u00e9s qui sont revenus aux bureaux ne sont pas toujours pr\u00eats \u00e0 se s\u00e9parer des outils de collaboration en ligne pratiques qu\u2019ils ont appris \u00e0 utiliser l\u2019ann\u00e9e derni\u00e8re. Mais comme c\u2019est souvent le cas, les nouveaux outils viennent avec des risques suppl\u00e9mentaires.<\/p>\n<h2>Qu\u2019est-ce qui pourrait mal tourner avec le partage de fichiers sur le Cloud ?<\/h2>\n<p>Les experts en cybers\u00e9curit\u00e9 voient g\u00e9n\u00e9ralement les outils de stockage ou de partage de fichiers d\u2019un mauvais \u0153il, ce qui peut se comprendre car l\u2019utilisation d\u2019un outil l\u00e9gitime contre le syst\u00e8me informatique de l\u2019entreprise est le cauchemar de n\u2019importe quel sp\u00e9cialiste de la s\u00e9curit\u00e9.<\/p>\n<p>Avant d\u2019utiliser une plateforme de partage de fichiers en ligne, envisagez les risques qui peuvent d\u00e9couler de cette id\u00e9e fausse\u00a0: les fichiers t\u00e9l\u00e9charg\u00e9s au sein de l\u2019entreprise ne repr\u00e9sentent aucun danger. Une plateforme de stockage et d\u2019\u00e9change de donn\u00e9es officiellement approuv\u00e9e par l\u2019entreprise est naturellement consid\u00e9r\u00e9e comme faisant partie de cette derni\u00e8re. Cependant, un fichier malveillant peut acc\u00e9der au syst\u00e8me de plusieurs fa\u00e7ons.<\/p>\n<ol>\n<li><strong>Erreur commise par un employ\u00e9.<\/strong> Il n\u2019y a pas que les nouveaux employ\u00e9s qui peuvent se faire pi\u00e9ger par les cybercriminels et t\u00e9l\u00e9charger un fichier malveillant re\u00e7u par e-mail sur le Cloud de l\u2019entreprise, les anciens employ\u00e9s \u00e9galement. Il peut arriver qu\u2019un employ\u00e9 t\u00e9l\u00e9charge un tel fichier sur la plateforme de partage juste pour demander l\u2019avis de ses coll\u00e8gues.<\/li>\n<li><strong>Mauvaise utilisation du stockage.<\/strong> Il fut un temps o\u00f9 les employ\u00e9s travaillaient sur le m\u00eame r\u00e9seau local et \u00e9changeaient des fichiers non professionnels (freeware, shareware, jeux et documents) sur les serveurs internes. Les vieilles habitudes ont la peau dure et beaucoup d\u2019entre eux continuent d\u2019utiliser les plateformes de partage de donn\u00e9es \u00e0 ces fins. Vous pouvez l\u2019interdire cat\u00e9goriquement, mais cette solution n\u2019est pas aussi bonne qu\u2019elle ne para\u00eet car cela incitera les employ\u00e9s \u00e0 utiliser des plateformes externes sur lesquelles vous n\u2019avez aucun contr\u00f4le. Avec cette interdiction, la menace reste toujours pr\u00e9sente, mais pas votre capacit\u00e9 \u00e0 la g\u00e9rer.<\/li>\n<li><strong>Mouvement lat\u00e9ral des logiciels malveillants.<\/strong> Les cybercriminels qui ont acc\u00e8s au dispositif d\u2019un employ\u00e9 peuvent utiliser la plateforme Cloud pour mener une attaque en chargeant un malware sur le Cloud.<\/li>\n<li><strong>Vengeance<\/strong>. Un ancien employ\u00e9 peur s\u2019en prendre \u00e0 ses anciens coll\u00e8gues ou \u00e0 l\u2019entreprise elle-m\u00eame en pla\u00e7ant des fichiers malveillants dans le syst\u00e8me.<\/li>\n<\/ol>\n<h2>Comment minimiser les risques li\u00e9s au stockage Cloud<\/h2>\n<p>Le risque plus \u00e9lev\u00e9 sur la surface d\u2019attaque n\u2019est pas une raison pour abandonner l\u2019utilisation des plateformes de stockage et de partage de donn\u00e9es. Vous devez juste choisir une plateforme qui vous permet d\u2019analyser les t\u00e9l\u00e9chargements afin de lutter contre les cybermenaces.<\/p>\n<p>Voici l\u2019outil qu\u2019il vous faut : <a href=\"https:\/\/www.kaspersky.fr\/scan-engine?icid=fr_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">Kaspersky Scan Engine<\/a>. La solution fournit une protection compl\u00e8te contre les malwares, les chevaux de Troie, les vers informatiques, les rootkit, les spywares ainsi que les adwares. Elle peut \u00e9galement scanner le trafic Web et v\u00e9rifier la r\u00e9putation des fichiers et des adresses Web. De plus, de nombreuses plateformes ont d\u00e9j\u00e0 int\u00e9gr\u00e9 notre technologie dans la leur.<\/p>\n<h2>Protection d\u2019ownCloud<\/h2>\n<p>Nous nous sommes associ\u00e9s cet \u00e9t\u00e9 avec la plateforme de partage de fichiers ownCloud et nous sommes ravis de vous informer que Kaspersky Scan Engine peut \u00eatre activ\u00e9 directement dans ownCloud, ce qui veut dire que vous pouvez scanner les donn\u00e9es directement dans le Cloud sans avoir besoin de les envoyer vers une plateforme ext\u00e9rieure pour le faire.<\/p>\n<p>Cela est possible gr\u00e2ce au protocole ICAP, qui nous a permis de d\u00e9placer le processus de num\u00e9risation vers un serveur s\u00e9par\u00e9 et qui nous permet d\u2019assurer votre s\u00e9curit\u00e9 sans nuire aux performances de la plateforme. Nous avons \u00e9galement simplifi\u00e9 la configuration, l\u2019entretien et la scalabilit\u00e9.<\/p>\n<p>Pour en savoir plus sur comment les produits et les services tiers utilisent les technologie de Kaspersky, visitez <a href=\"https:\/\/www.kaspersky.fr\/scan-engine?icid=fr_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder_______\" target=\"_blank\" rel=\"noopener\">la page Web sur notre produit Kaspersky Scan Engine<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Poss\u00e9der une plateforme de stockage et de partage de fichiers peut repr\u00e9senter un risque suppl\u00e9mentaire en ce qui concerne la s\u00e9curit\u00e9 de l\u2019entreprise. <\/p>\n","protected":false},"author":2706,"featured_media":17431,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[122,3835,320],"class_list":{"0":"post-17430","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-cloud","9":"tag-fichiers","10":"tag-protection-des-donnees"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/owncloud-scanengine-integration\/17430\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/owncloud-scanengine-integration\/23137\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/owncloud-scanengine-integration\/18619\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/owncloud-scanengine-integration\/25136\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/owncloud-scanengine-integration\/23160\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/owncloud-scanengine-integration\/22513\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/owncloud-scanengine-integration\/25782\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/owncloud-scanengine-integration\/25258\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/owncloud-scanengine-integration\/31221\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/owncloud-scanengine-integration\/9907\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/owncloud-scanengine-integration\/41040\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/owncloud-scanengine-integration\/17895\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/owncloud-scanengine-integration\/15130\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/owncloud-scanengine-integration\/31516\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/owncloud-scanengine-integration\/27374\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/owncloud-scanengine-integration\/24178\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/owncloud-scanengine-integration\/29514\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/owncloud-scanengine-integration\/29319\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/protection-des-donnees\/","name":"protection des donn\u00e9es"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/17430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/2706"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=17430"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/17430\/revisions"}],"predecessor-version":[{"id":17434,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/17430\/revisions\/17434"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/17431"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=17430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=17430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=17430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}