{"id":18431,"date":"2022-01-17T10:54:00","date_gmt":"2022-01-17T08:54:00","guid":{"rendered":"https:\/\/www.kaspersky.fr\/blog\/?p=18431"},"modified":"2022-01-17T10:54:00","modified_gmt":"2022-01-17T08:54:00","slug":"how-to-control-your-cookies","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/how-to-control-your-cookies\/18431\/","title":{"rendered":"Comment g\u00e9rer les cookies : test dans la vie r\u00e9elle"},"content":{"rendered":"<p>De nos jours, lorsque vous ouvrez un site Web, une banni\u00e8re s\u2019affiche imm\u00e9diatement en bas de l\u2019\u00e9cran et vous demande \u00ab\u00a0d\u2019accepter les cookies\u00a0\u00bb. \u00a0En g\u00e9n\u00e9ral, les utilisateurs acceptent, pour se d\u00e9barrasser d\u00e8s que possible de cette fen\u00eatre ennuyante. Beaucoup ne savent pas s\u2019ils peuvent refuser les cookies ou comment les configurer. Nous avons d\u00e9cid\u00e9 de faire un test pour vous montrer comment vous pouvez contr\u00f4ler les cookies et ce qui se passe si vous acceptez sans r\u00e9fl\u00e9chir.<\/p>\n<h2>Que sont les cookies et qu\u2019en faites-vous ?<\/h2>\n<p>Tous les sites recueillent des informations sur vous et sur vos activit\u00e9s, et stockent les informations sur votre dispositif sous la forme de petits fichiers. Ce sont les cookies.<\/p>\n<p>Les cookies remplissent trois fonctions principales\u00a0:<\/p>\n<ul>\n<li>Rendre le site plus agr\u00e9able pour les utilisateurs,<\/li>\n<li>Aider le site \u00e0 mieux fonctionner,<\/li>\n<li>Suivre les activit\u00e9s des visiteurs\u00a0;<\/li>\n<\/ul>\n<p>Commen\u00e7ons par la commodit\u00e9. Les cookies vous identifient sur un site et sauvegardent vos param\u00e8tres, le cas \u00e9ch\u00e9ant. Par exemple, le site de r\u00e9servation d\u2019un h\u00f4tel peut savoir en quelle monnaie vous avez pay\u00e9, et si vous cochez l\u2019option \u00a0\u00bb\u00a0Se souvenir de moi\u00a0\u00a0\u00bb sur la page de connexion d\u2019un r\u00e9seau social, vous n\u2019aurez plus \u00e0 saisir votre identifiant et votre mot de passe. Lorsque vous consultez \u00e0 nouveau le site, ce dernier analyse votre dispositif pour voir s\u2019il y a des cookies associ\u00e9s, vous reconna\u00eet et ouvre automatiquement votre compte.<\/p>\n<p>Pourtant, en plus d\u2019offrir des fonctionnalit\u00e9s qui s\u2019av\u00e8rent utiles pour les visiteurs, les cookies permettent aux services de collecter des <a href=\"https:\/\/www.kaspersky.fr\/blog\/web-tracking-in-numbers\/5624\/\" target=\"_blank\" rel=\"noopener\">donn\u00e9es sur les utilisateurs<\/a> afin de leur sugg\u00e9rer des choses qui pourraient les int\u00e9resser et, \u00e9videmment, d\u2019afficher des publicit\u00e9s cibl\u00e9es. Les cookies appartiennent aux propri\u00e9taires du site mais aussi aux entreprises avec lesquelles ils ont des accords de partenariat. Il s\u2019agit alors des <em>cookies tiers<\/em>, et c\u2019est \u00e0 cause d\u2019eux que beaucoup disent que les cookies sont des outils qui permettent de traquer les utilisateurs.<\/p>\n<p>\u00c9tant donn\u00e9 que les cookies recueillent des informations personnelles sujettes \u00e0 protection, de nombreux pays ont pris des mesures l\u00e9gislatives et r\u00e9glementaires pour obliger les propri\u00e9taires de sites \u00e0 obtenir l\u2019accord des utilisateurs. La <a href=\"https:\/\/edps.europa.eu\/data-protection\/our-work\/subjects\/directive-vie-privee-et-communications-electroniques_fr\" target=\"_blank\" rel=\"noopener nofollow\">Directive 2002\/58\/EC du Parlement europ\u00e9en et du Conseil<\/a> est l\u2019une d\u2019elles.<\/p>\n<h2>Tout accepter<\/h2>\n<p>Apr\u00e8s avoir ouvert le site pour une quelconque raison, les utilisateurs ont tendance \u00e0 cliquer imm\u00e9diatement sur <em>OK<\/em> ou <em>Accepter<\/em> afin de pouvoir fermer rapidement la fen\u00eatre, m\u00eame si cela signifie qu\u2019ils acceptent qu\u2019une certaine personne puisse recueillir quelques informations. Certaines personnes prennent le temps de lire la notification, mais peu passent \u00e0 l\u2019\u00e9tape suivante et configurent les cookies du site.<\/p>\n<p>Les d\u00e9veloppeurs ont tendance \u00e0 encourager les utilisateurs \u00e0 cliquer sur <em>Tout accepter<\/em>, notamment en affichant un gros bouton qui attire l\u2019attention, alors que le bouton <em>Param\u00e8tres<\/em> passe plus inaper\u00e7u. Les astuces utilis\u00e9es par certains sites qui cherchent \u00e0 compliquer la gestion des cookies ont d\u2019ores et d\u00e9j\u00e0 attir\u00e9 l\u2019attention des <a href=\"https:\/\/www.bbc.com\/news\/technology-57306802\" target=\"_blank\" rel=\"noopener nofollow\">d\u00e9fenseurs de la vie priv\u00e9e<\/a>.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kis-trial-privacy\">\n<h2>Notre test avec les cookies<\/h2>\n<p>Nous avons r\u00e9alis\u00e9 un test afin de d\u00e9terminer comment fonctionne la configuration des cookies. Nous cherchons avant tout \u00e0 r\u00e9pondre aux questions suivantes\u00a0:<\/p>\n<ul>\n<li>Les sites avertissent-ils les utilisateurs qu\u2019ils utilisent des cookies\u00a0?<\/li>\n<li>Les utilisateurs peuvent-ils refuser les cookies\u00a0?<\/li>\n<li>Comment les param\u00e8tres choisis par les utilisateurs affectent-ils le nombre de cookies conserv\u00e9s\u00a0?<\/li>\n<li>Les cookies peuvent-ils \u00eatre configur\u00e9s rapidement et facilement\u00a0?<\/li>\n<\/ul>\n<p>Nous avons s\u00e9lectionn\u00e9 32 sites pour notre test\u00a0: 10 sites de m\u00e9dias de masse, 8 d\u2019entreprises priv\u00e9es, 4 d\u2019organisation culturelles et sportives, 4 de sites \u00e9ducatifs, 2 de sites gouvernementaux et 4 d\u2019autres types.<\/p>\n<p>Avant de visiter chaque site, nous avons effac\u00e9 tous les cookies de l\u2019ordinateur pour que le site pense que nous le consultions pour la premi\u00e8re fois. Nous avons ensuite ouvert le site, puis v\u00e9rifi\u00e9 si les cookies \u00e9taient stock\u00e9s sur le dispositif, et si oui lesquels. Si la fen\u00eatre qui s\u2019ouvrait nous proposait de param\u00e9trer les cookies, nous v\u00e9rifions quels cookies \u00e9taient activ\u00e9s et d\u00e9sactiv\u00e9s par d\u00e9faut.<\/p>\n<h3>Est-il possible de configurer les cookies sur tous les sites ?<\/h3>\n<p>Sur les 32 sites \u00e9tudi\u00e9s, 14 n\u2019ont pas indiqu\u00e9 aux utilisateurs qu\u2019ils utilisent des cookies ou affich\u00e9 l\u2019option qui permet de les configurer. De plus, juste apr\u00e8s avoir ouvert les sites, des cookies \u00e9taient sauvegard\u00e9s sur le dispositif.<\/p>\n<p>Nous avons alors v\u00e9rifi\u00e9 si les sites proposaient de g\u00e9rer les cookies d\u2019une quelconque mani\u00e8re. Pour ce faire, nous avons minutieusement lu la politique de confidentialit\u00e9 et d\u00e9couvert si nous pouvions, du moins en th\u00e9orie, emp\u00eacher les sites de collecter et d\u2019utiliser les donn\u00e9es. Suivant les sites, deux options s\u2019offraient \u00e0 nous\u00a0: contacter directement l\u2019entreprise marketing avec laquelle le site du propri\u00e9taire travaille, ou \u00e9crire aux administrateurs du site pour leur demander de ne pas tracer notre activit\u00e9. En pratique, ces m\u00e9thodes ne sont pas tr\u00e8s commodes pour vous prot\u00e9ger.<\/p>\n<h3>Que se passe-t-il si le site vous laisse configurer les cookies ?<\/h3>\n<p>Sur ces 32 sites, 18 (soit un peu plus de la moiti\u00e9) nous proposaient de personnaliser les cookies. Pourtant, cela n\u2019\u00e9tait possible que pour certains cookies et ils nous demandaient de maintenir ceux consid\u00e9r\u00e9s comme \u00a0\u00bb\u00a0n\u00e9cessaires\u00a0\u00ab\u00a0. Parmi ces 18 sites, la plupart (14) remerciait d\u2019une certaine fa\u00e7on les utilisateurs qui prenaient le temps d\u2019ouvrir les param\u00e8tres\u00a0: les cookies publicitaires \u00e9taient imm\u00e9diatement d\u00e9sactiv\u00e9s.<\/p>\n<p>La mauvaise surprise \u00e9tait que sept sites imposaient les cookies aux utilisateurs. En d\u2019autres termes, nous ne pouvions m\u00eame pas choisir si nous voulions accepter tous les cookies ou d\u2019abord voir les param\u00e8tres. Le site avait d\u00e9j\u00e0 enregistr\u00e9 des donn\u00e9es sur nous.<\/p>\n<p>Si un site agissait correctement et nous laissait d\u00e9cider, nous ouvrions les param\u00e8tres et essayions de d\u00e9sactiver tous les cookies. Lorsque nous agissions ainsi, entre un et trois cookies \u00e9taient sauvegard\u00e9s sur l\u2019ordinateur. Si nous acceptions tous les cookies, 20 \u00e0 30 cookies \u00e9taient enregistr\u00e9s. Cette diff\u00e9rence de taille montre clairement que vous devez ouvrir les param\u00e8tres et les raisons sont \u00e9videntes.<\/p>\n<h3>Nous avons essay\u00e9 de d\u00e9sactiver les cookies dans les param\u00e8tres du navigateur<\/h3>\n<p>Nous savons que les cookies peuvent \u00eatre refus\u00e9s depuis les param\u00e8tres du site, mais cette m\u00e9thode n\u2019est pas pratique et est ennuyeuse. Heureusement, il y a une autre option. Vous pouvez bloquer les cookies tiers (principalement publicitaires) ou d\u00e9sactiver tous les cookies depuis les param\u00e8tres du navigateur. Il faut reconna\u00eetre que certains sites pourraient ne pas bien fonctionner si vous d\u00e9sactivez tous les cookies.<\/p>\n<p>D\u2019autre part, n\u2019oubliez pas que de nombreux navigateurs proposent le <a href=\"https:\/\/www.kaspersky.fr\/blog\/incognito-mode-faq\/6971\/\" target=\"_blank\" rel=\"noopener\">mode de navigation priv\u00e9e<\/a>. Si vous l\u2019utilisez, les sites peuvent installer des cookies mais le navigateur les supprime automatiquement lorsque vous quittez le site. Cette fonctionnalit\u00e9 est particuli\u00e8rement utile, par exemple si vous devez utiliser un ordinateur qui n\u2019est pas le v\u00f4tre et que les param\u00e8tres de cookies du navigateur ne d\u00e9pendent pas de vous.<\/p>\n<h2>Les cookies ne sont pas les seuls outils de pistage<\/h2>\n<p>Tous ces param\u00e8tres, options de blocage et modes cherchent \u00e0 emp\u00eacher les tiers de nous traquer. Nous avons examin\u00e9 en profondeur les cookies, mais ces param\u00e8tres sont-ils suffisants pour prot\u00e9ger les utilisateurs\u00a0? Malheureusement non. Les sites ont un nombre surprenant de <a href=\"https:\/\/www.kaspersky.fr\/blog\/internet-ads-103\/6412\/\" target=\"_blank\" rel=\"noopener\">m\u00e9thodes pour traquer les utilisateurs<\/a>.<\/p>\n<p>Il y a d\u2019autres outils pour un suivi publicitaire complet. Par exemple, <a href=\"https:\/\/www.kaspersky.fr\/plus?icid=fr_bb2022-kdplacehd_acq_ona_smm__onl_b2c_kdaily_lnk_sm-team___kplus___\" target=\"_blank\" rel=\"noopener\">Kaspersky Internet Security<\/a>\u00a0a un module de <em>Navigation priv\u00e9e<\/em> qui bloque le pistage. Lors de notre test, nous avons utilis\u00e9 la solution et cette derni\u00e8re nous a toujours avertis lorsqu\u2019un site essayait de nous traquer, m\u00eame si nous avions d\u00e9sactiv\u00e9 les cookies dans le navigateur, et a bloqu\u00e9 les demandes. R\u00e9sultat, si vous voulez \u00eatre certain que personne ne peut traquer votre activit\u00e9 en ligne, il vaut mieux utiliser une protection suppl\u00e9mentaire.<\/p>\n<h2>Conclusions<\/h2>\n<p>Pour r\u00e9sumer, notre test a r\u00e9v\u00e9l\u00e9 que la meilleure solution n\u2019est pas d\u2019ouvrir les param\u00e8tres de chaque site, mais plut\u00f4t de tous les configurer dans le navigateur. Il convient d\u2019utiliser le menu des param\u00e8tres pour bloquer les cookies. Si vous en avez besoin, vous pouvez faire une exception pour certains sites. Enfin, configurez la Navigation Priv\u00e9e pour vous prot\u00e9ger contre les tentatives de pistage.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"kis-trial-privacy\">\n","protected":false},"excerpt":{"rendered":"<p>Nous vous expliquons comment les cookies affectent votre vie priv\u00e9e en ligne.<\/p>\n","protected":false},"author":2049,"featured_media":18432,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3798,1868],"tags":[180,4254,325,141,2703,2647,227],"class_list":{"0":"post-18431","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-confidentialite","8":"category-privacy","9":"tag-confidentialite","10":"tag-cookie","11":"tag-cookies","12":"tag-kaspersky-internet-security","13":"tag-navigateurs","14":"tag-sites-internet","15":"tag-vie-privee"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/how-to-control-your-cookies\/18431\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/how-to-control-your-cookies\/23831\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/how-to-control-your-cookies\/19330\/"},{"hreflang":"ar","url":"https:\/\/me.kaspersky.com\/blog\/how-to-control-your-cookies\/9800\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/how-to-control-your-cookies\/26060\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/how-to-control-your-cookies\/24029\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/how-to-control-your-cookies\/23745\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/how-to-control-your-cookies\/26710\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/how-to-control-your-cookies\/26312\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/how-to-control-your-cookies\/32191\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/how-to-control-your-cookies\/10454\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/how-to-control-your-cookies\/43303\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/how-to-control-your-cookies\/18809\/"},{"hreflang":"pl","url":"https:\/\/plblog.kaspersky.com\/how-to-control-your-cookies\/15692\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/how-to-control-your-cookies\/27979\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/how-to-control-your-cookies\/32317\/"},{"hreflang":"nl","url":"https:\/\/www.kaspersky.nl\/blog\/how-to-control-your-cookies\/28022\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/how-to-control-your-cookies\/24779\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/how-to-control-your-cookies\/30177\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/how-to-control-your-cookies\/29968\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/vie-privee\/","name":"vie priv\u00e9e"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/18431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/2049"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=18431"}],"version-history":[{"count":1,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/18431\/revisions"}],"predecessor-version":[{"id":18433,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/18431\/revisions\/18433"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/18432"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=18431"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=18431"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=18431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}