{"id":19198,"date":"2022-07-22T16:59:21","date_gmt":"2022-07-22T14:59:21","guid":{"rendered":"https:\/\/www.kaspersky.fr\/blog\/?p=19198"},"modified":"2022-07-25T10:49:38","modified_gmt":"2022-07-25T08:49:38","slug":"odor-based-authentication","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/odor-based-authentication\/19198\/","title":{"rendered":"Soufflez ! Une biom\u00e9trie inhabituelle bas\u00e9e sur votre odeur"},"content":{"rendered":"<p>Un groupe de chercheurs de plusieurs universit\u00e9s japonaises a r\u00e9cemment publi\u00e9 une <a href=\"https:\/\/pubs.rsc.org\/en\/content\/articlelanding\/2022\/CC\/D1CC06384G\" target=\"_blank\" rel=\"noopener nofollow\">\u00e9tude int\u00e9ressante<\/a> qui d\u00e9crit un tout nouveau concept d\u2019authentification biom\u00e9trique\u00a0: l\u2019analyse de l\u2019haleine. L\u2019id\u00e9e ressemble \u00e0 celle des \u00e9thylotests auxquels les conducteurs, comme vous et moi, doivent parfois se soumettre, mais qui sont un test r\u00e9gulier pour les chauffeurs professionnels et les gens qui ont d\u2019autres professions dangereuses.<\/p>\n<p>Pourtant, c\u2019est le seul point commun. La m\u00e9thode propos\u00e9e par cette \u00e9tude est beaucoup plus complexe. Pour commencer, elle doit identifier plusieurs composants chimiques diff\u00e9rents dans l\u2019haleine. De plus, la proc\u00e9dure doit permettre de d\u00e9terminer la concentration de certaines substances et de faire la diff\u00e9rence entre une personne et une autre gr\u00e2ce \u00e0 son \u00a0\u00bb\u00a0empreinte respiratoire\u00a0\u00ab\u00a0.<\/p>\n<h2><strong>Mais\u2026 pourquoi ?<\/strong><\/h2>\n<p>Ce qu\u2019il y a de bien avec le travail de ces chercheurs est qu\u2019ils n\u2019ont pas \u00e0 se fixer d\u2019objectifs pratiques\u00a0! Autrement dit, ils le font simplement parce qu\u2019ils en ont envie.<\/p>\n<p>De fa\u00e7on g\u00e9n\u00e9rale, l\u2019analyse de l\u2019haleine est consid\u00e9r\u00e9e comme un domaine de pointe de la recherche. De gros progr\u00e8s ont \u00e9t\u00e9 faits dans ce secteur gr\u00e2ce \u00e0 l\u2019utilisation de l\u2019apprentissage automatique pour traiter les donn\u00e9es, par exemple pour <a href=\"https:\/\/www.researchgate.net\/publication\/341693985_Medical_diagnosis_by_breath_analysis_odor_sensors\" target=\"_blank\" rel=\"noopener nofollow\">diagnostiquer les maladies respiratoires<\/a>. Si les syst\u00e8mes d\u2019analyse et les algorithmes d\u2019apprentissage existent d\u00e9j\u00e0, pourquoi ne pas effectuer des recherches sur la possibilit\u00e9 d\u2019utiliser l\u2019haleine comme m\u00e9thode d\u2019authentification\u00a0?<\/p>\n<h2><strong>Quel est le fonctionnement de cette authentification fond\u00e9e sur l\u2019odeur ?<\/strong><\/h2>\n<p>Lors de la premi\u00e8re \u00e9tape, on recueille l\u2019air exhal\u00e9 par les sujets de l\u2019\u00e9tude. Ensuite, l\u2019air passe par un analyseur de 16 canaux. Les chercheurs ont essay\u00e9 d\u2019obtenir les donn\u00e9es en utilisant moins de capteurs mais l\u2019efficacit\u00e9 de la m\u00e9thode a imm\u00e9diatement baiss\u00e9.<\/p>\n<p>Chaque canal d\u00e9tecte s\u00e9par\u00e9ment un composant chimique dans l\u2019air. L\u2019analyseur enregistre l\u2019intensit\u00e9 du signal des capteurs et l\u2019\u00e9volution de l\u2019intensit\u00e9 au cours du temps.<\/p>\n<div id=\"attachment_19195\" style=\"width: 1606px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19195\" class=\"wp-image-19195 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2022\/07\/22165147\/odor-based-authentication-1.png\" alt=\"Fonctionnement du syst\u00e8me d'authentification par l'haleine \u00e0 ce stade.\" width=\"1596\" height=\"961\"><p id=\"caption-attachment-19195\" class=\"wp-caption-text\">Fonctionnement du syst\u00e8me d\u2019authentification par l\u2019haleine \u00e0 ce stade. <a>Source<\/a>.<\/p><\/div>\n<p>\u00a0<\/p>\n<p>Par cons\u00e9quent, une grande quantit\u00e9 de donn\u00e9es est obtenue puis trait\u00e9e par un algorithme d\u2019apprentissage automatique. Apr\u00e8s avoir \u00e9t\u00e9 entra\u00een\u00e9 sur les donn\u00e9es du test, l\u2019algorithme peut identifier de mani\u00e8re assez pr\u00e9cise la personne \u00e0 partir de son haleine.<\/p>\n<h2><strong>Cette m\u00e9thode est-elle fiable ?<\/strong><\/h2>\n<p>Les scientifiques japonais ont pu identifier correctement une personne \u00e0 partir de son haleine dans 97 % des cas. Peut-on consid\u00e9rer que cette \u00e9tude est un succ\u00e8s\u00a0? Nous n\u2019avons pas assez de donn\u00e9es pour r\u00e9pondre \u00e0 cette question.<\/p>\n<p>Nous pouvons comparer ces performances g\u00e9n\u00e9rales avec les donn\u00e9es de cette <a href=\"https:\/\/www.researchgate.net\/publication\/306072438_Review_Paper_on_Applications_of_Principal_Component_Analysis_in_Multimodal_Biometrics_System\" target=\"_blank\" rel=\"noopener nofollow\">\u00e9tude<\/a> r\u00e9alis\u00e9e en 2016 qui a, entre autres, analys\u00e9 les caract\u00e9ristiques pour l\u2019\u00e9valuation de syst\u00e8mes biom\u00e9triques. Au premier abord, cette m\u00e9thode bas\u00e9e sur l\u2019haleine est aussi fiable que les lecteurs d\u2019empreinte digitale et est l\u00e9g\u00e8rement sup\u00e9rieure aux technologies de reconnaissance faciale.<\/p>\n<div id=\"attachment_19196\" style=\"width: 1672px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-19196\" class=\"wp-image-19196 size-full\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2022\/07\/22165154\/odor-based-authentication-2.png\" alt=\"Taux de pr\u00e9cision de diverses technologies d'authentification biom\u00e9trique.\" width=\"1662\" height=\"427\"><p id=\"caption-attachment-19196\" class=\"wp-caption-text\">Taux de pr\u00e9cision de diverses technologies d\u2019authentification biom\u00e9trique. <a>Source<\/a>.<\/p><\/div>\n<p>\u00a0<\/p>\n<p>Pourtant, comme cela a \u00e9t\u00e9 soulign\u00e9 dans l\u2019\u00e9tude r\u00e9alis\u00e9e en 2016 et mentionn\u00e9e auparavant, il est crucial de prendre en compte le taux de faux n\u00e9gatifs (\u00e9chec de la reconnaissance d\u2019utilisateurs enregistr\u00e9s) et de faux positifs (identification d\u2019un \u00e9tranger). Nous rencontrons le probl\u00e8me des faux n\u00e9gatifs au quotidien lorsque notre smartphone ne nous reconna\u00eet pas, et ce n\u2019est pas si grave que \u00e7a. Quant aux faux positifs, ils ne sont pas conseill\u00e9s et il convient d\u2019y rem\u00e9dier le plus rapidement possible. Cela \u00e9tant dit, cette \u00e9tude ne donne pas suffisamment de renseignements d\u00e9taill\u00e9s sur les performances de l\u2019authentification par l\u2019haleine dans ce domaine.<\/p>\n<p>Il est \u00e9galement int\u00e9ressant de noter que les chercheurs de cette analyse de l\u2019haleine ont r\u00e9f\u00e9renc\u00e9 des \u00e9tudes pr\u00e9c\u00e9dentes, dont certaines qui leur appartiennent, et ont enregistr\u00e9 les progr\u00e8s, par exemple, en les comparant avec l\u2019analyse chimique de la transpiration. Oui, des recherches ont aussi \u00e9t\u00e9 faites sur l\u2019authentification par la transpiration\u00a0!<\/p>\n<h2><strong>Cette m\u00e9thode est-elle pratique ?<\/strong><\/h2>\n<p>Les chercheurs ont utilis\u00e9 un \u00e9quipement de laboratoire co\u00fbteux que vous ne pouvez pas tout simplement int\u00e9grer dans un ordinateur portable, un smartphone ou une voiture. M\u00eame s\u2019il est actuellement possible d\u2019installer un syst\u00e8me qui bloque le d\u00e9marrage du v\u00e9hicule si de l\u2019alcool est d\u00e9tect\u00e9 dans l\u2019air, le mat\u00e9riel n\u00e9cessaire pour une authentification par l\u2019haleine est beaucoup plu sophistiqu\u00e9 et cher.<\/p>\n<p>Lorsque vous lisez minutieusement l\u2019\u00e9tude, vous trouvez encore plus de raisons qui expliquent pourquoi, \u00e0 court terme, nous n\u2019allons pas souffler dans nos smartphones pour les d\u00e9verrouiller. Comme nous l\u2019avons d\u00e9j\u00e0 dit, les chercheurs ont \u00e9tudi\u00e9 la d\u00e9croissance radioactive de certains composants chimiques pour que le syst\u00e8me soit plus pr\u00e9cis\u2026 et cela peut prendre jusqu\u2019\u00e0 40 minutes\u00a0!<\/p>\n<p>Ce n\u2019est pas tout. Les participants \u00e0 l\u2019\u00e9tude n\u2019ont pas pu manger six heures avant l\u2019exp\u00e9rience. Les auteurs expliquent qu\u2019un repas r\u00e9cent pourrait jouer sur la pr\u00e9cision des r\u00e9sultats, tout comme les composants trouv\u00e9s dans l\u2019haleine qui accompagnent grand nombre de maladies. Il semblerait que le doux ar\u00f4me de l\u2019alcool ou qu\u2019un simple rhume puissent fausser les r\u00e9sultats.<\/p>\n<p>Pour conclure, ici et maintenant, cette technologie n\u2019a pas vraiment d\u2019utilit\u00e9 pratique. En revanche, il s\u2019agit sans aucun doute d\u2019un domaine de recherche int\u00e9ressant qui pourrait \u00eatre d\u00e9velopp\u00e9 \u00e0 l\u2019avenir. Si ce n\u2019est pas sous la forme d\u2019une authentification qui vous demande de \u00a0\u00bb\u00a0souffler dans le tube\u00a0\u00ab\u00a0, ce pourrait au moins \u00eatre utile pour les syst\u00e8mes avanc\u00e9s de diagnostic m\u00e9dical.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"earth-2050\">\n","protected":false},"excerpt":{"rendered":"<p>Nous analysons une \u00e9tude r\u00e9cente sur une authentification biom\u00e9trique qui analyse l\u2019haleine.<\/p>\n","protected":false},"author":665,"featured_media":19197,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1869],"tags":[1214,587,527],"class_list":{"0":"post-19198","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-technology","8":"tag-2fa","9":"tag-authentification","10":"tag-technologie"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/odor-based-authentication\/19198\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/odor-based-authentication\/24391\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/odor-based-authentication\/19857\/"},{"hreflang":"en-us","url":"https:\/\/usa.kaspersky.com\/blog\/odor-based-authentication\/26781\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/odor-based-authentication\/24690\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/odor-based-authentication\/25078\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/odor-based-authentication\/27427\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/odor-based-authentication\/27097\/"},{"hreflang":"ru","url":"https:\/\/www.kaspersky.ru\/blog\/odor-based-authentication\/33531\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/odor-based-authentication\/10860\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/odor-based-authentication\/44945\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/odor-based-authentication\/19756\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/odor-based-authentication\/29065\/"},{"hreflang":"ru-kz","url":"https:\/\/blog.kaspersky.kz\/odor-based-authentication\/25263\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/odor-based-authentication\/30756\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/odor-based-authentication\/30503\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/2fa\/","name":"2FA"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/19198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/665"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=19198"}],"version-history":[{"count":5,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/19198\/revisions"}],"predecessor-version":[{"id":19209,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/19198\/revisions\/19209"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/19197"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=19198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=19198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=19198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}