{"id":21170,"date":"2023-11-08T10:13:20","date_gmt":"2023-11-08T08:13:20","guid":{"rendered":"https:\/\/www.kaspersky.fr\/blog\/?p=21170"},"modified":"2023-11-10T17:30:46","modified_gmt":"2023-11-10T15:30:46","slug":"gen-ai-worries","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/gen-ai-worries\/21170\/","title":{"rendered":"Les dirigeants doivent-ils s&rsquo;inqui\u00e9ter de l&rsquo;IA ?"},"content":{"rendered":"<p>L\u2019intelligence artificielle est devenue un sujet \u00e0 la mode ces derniers temps, avec des start-ups du monde entier qui sautent dans le train de l\u2019I.A., dans l\u2019espoir de cr\u00e9er le prochain ChatGPT. Mais tandis que la course \u00e0 la cr\u00e9ation de la prochaine grande innovation se poursuit, les employeurs s\u2019interrogent sur la mani\u00e8re dont les outils actuels seront utilis\u00e9s (et peut-\u00eatre d\u00e9tourn\u00e9s) au sein de leur entreprise.<\/p>\n<p>Les entreprises sont-elles en train de sombrer dans un cauchemar en mati\u00e8re de cybers\u00e9curit\u00e9, ou les inqui\u00e9tudes li\u00e9es \u00e0 cette nouvelle technologie sont-elles exag\u00e9r\u00e9es ? Nous avons r\u00e9cemment men\u00e9 une enqu\u00eate en demandant \u00e0 des chefs d\u2019entreprise ce qu\u2019ils pensaient de l\u2019IA g\u00e9n\u00e9rative et de son utilisation dans leur entreprise.<\/p>\n<h2>Une v\u00e9ritable inqui\u00e9tude ?<\/h2>\n<p>L\u2019I.A. g\u00e9n\u00e9rative n\u2019est pas un risque pour la s\u00e9curit\u00e9 au m\u00eame titre qu\u2019un serveur ou un terminal non conforme. Pour bien comprendre cela, il faut d\u2019abord comprendre comment fonctionne l\u2019I.A. g\u00e9n\u00e9rative.<\/p>\n<p>Pour fonctionner efficacement, l\u2019IA s\u2019appuie sur les donn\u00e9es fournies par l\u2019utilisateur. \u00c0 partir de ces donn\u00e9es, l\u2019outil apprend et affine ses r\u00e9sultats. Bien que l\u2019utilisation de l\u2019IA g\u00e9n\u00e9rative pr\u00e9sente de nombreux avantages, le traitement correct de la propri\u00e9t\u00e9 intellectuelle ou des donn\u00e9es hautement sensibles dans un contexte professionnel n\u00e9cessite une attention particuli\u00e8re.<\/p>\n<p>Il est donc possible que le personnel utilise mal les outils d\u2019IA et partage des donn\u00e9es sensibles ou de la propri\u00e9t\u00e9 intellectuelle avec un tiers. Outre le fait que vous pourriez rencontrer des probl\u00e8mes juridiques tels dans le cadre du RGPD, vous pourriez vous retrouver dans une situation o\u00f9 votre entreprise partage des donn\u00e9es priv\u00e9es avec un outil qui pourrait \u00eatre utilis\u00e9 pour devenir plus intelligent. D\u2019une mani\u00e8re g\u00e9n\u00e9rale, l\u2019inqui\u00e9tude provient donc de la protection de la vie priv\u00e9e et des donn\u00e9es plut\u00f4t que des probl\u00e8mes de s\u00e9curit\u00e9 \u00ab\u00a0traditionnels\u00a0\u00bb auxquels les \u00e9quipes informatiques sont habitu\u00e9es.<\/p>\n<h2><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2023\/11\/08110738\/TI_AI_FR_Vdef.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21178\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2023\/11\/08110738\/TI_AI_FR_Vdef.png\" alt=\"\" width=\"1200\" height=\"628\"><\/a><br>\nChaque m\u00e9daille a son revers<\/h2>\n<p>Notre \u00e9tude montre qu\u2019environ un quart des chefs d\u2019entreprise tels que les PDG (26 %) utilisent d\u00e9j\u00e0 eux-m\u00eames des outils tels que ChatGPT.<\/p>\n<p>Bien que de nombreuses personnes interrog\u00e9es pensent que l\u2019IA est d\u00e9j\u00e0 utilis\u00e9e dans leur entreprise, la plupart d\u2019entre elles n\u2019ont pas l\u2019intention de faire quoi que ce soit \u00e0 ce sujet. En fait, \u00e0 peine plus d\u2019un quart des personnes interrog\u00e9es utilisent elles-m\u00eames l\u2019IA dans leurs activit\u00e9s quotidiennes.<\/p>\n<h2>Quelle est la solution ?<\/h2>\n<p>Alors que nous dissertons sur les enjeux de l\u2019I.A. g\u00e9n\u00e9rative, quelles sont les solutions pragmatiques pour que les entreprises puissent continuer \u00e0 utiliser des outils tels que celui-ci, tout en att\u00e9nuant les risques.<\/p>\n<p>Pour comprendre cela, il faut remonter un peu en arri\u00e8re. Il y a dix ans, le BYOD (Bring Your Own Device \u2013 Apportez votre propre appareil) a \u00e9t\u00e9 salu\u00e9 comme un changement de cap pour les entreprises, leur permettant de r\u00e9duire les co\u00fbts et la maintenance. Cependant, les entreprises se sont rapidement rendu compte que le BYOD posait plusieurs probl\u00e8mes, notamment le fait de ne pas avoir une vue d\u2019ensemble des appareils pr\u00e9sents sur leur r\u00e9seau et d\u2019autres probl\u00e8mes li\u00e9s \u00e0 la confidentialit\u00e9 et \u00e0 la s\u00e9curit\u00e9 des donn\u00e9es. Par cons\u00e9quent, dans de nombreuses entreprises, le BYOD a \u00e9t\u00e9 restreint ou bloqu\u00e9, ou le personnel a d\u00fb s\u2019assurer que les \u00e9quipes informatiques avaient une visibilit\u00e9 sur les appareils.<\/p>\n<p>Quel est donc le rapport avec l\u2019I.A. G\u00e9n\u00e9rative ? Eh bien, comme l\u2019a dit John C. Maxwell : \u00ab\u00a0On ne peut pas faire confiance \u00e0 ce que l\u2019on ne comprend pas\u00a0\u00bb. Les chefs d\u2019entreprise doivent en savoir plus sur les avantages et les inconv\u00e9nients de l\u2019I.A. g\u00e9n\u00e9rative pour d\u00e9terminer si elle m\u00e9rite vraiment une place dans leur entreprise.<\/p>\n<p>Pour en savoir plus sur nos conclusions, vous pouvez lire le rapport complet <a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/86\/2023\/10\/25123633\/Report-ENG-Gen-AI-Business-Infiltration-Oct-2023-v2.2.pdf\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;IA g\u00e9n\u00e9rative est d\u00e9sormais un outil r\u00e9pandu pour beaucoup, mais les chefs d&rsquo;entreprise doivent-ils s&rsquo;en pr\u00e9occuper ?<\/p>\n","protected":false},"author":437,"featured_media":21171,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[136,1261,204,1003,61,828,227,322],"class_list":["post-21170","post","type-post","status-publish","format-standard","has-post-thumbnail","category-news","tag-entreprise","tag-etudes","tag-menaces","tag-recherches","tag-securite","tag-securite-des-entreprises","tag-vie-privee","tag-vulnerabilites"],"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/gen-ai-worries\/21170\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/gen-ai-worries\/29502\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/gen-ai-worries\/28263\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/gen-ai-worries\/30747\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/securite-des-entreprises\/","name":"s\u00e9curit\u00e9 des entreprises"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/21170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/437"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=21170"}],"version-history":[{"count":6,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/21170\/revisions"}],"predecessor-version":[{"id":21180,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/21170\/revisions\/21180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/21171"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=21170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=21170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=21170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}