{"id":22288,"date":"2024-10-10T09:25:46","date_gmt":"2024-10-10T07:25:46","guid":{"rendered":"https:\/\/www.kaspersky.fr\/blog\/?p=22288"},"modified":"2024-10-10T09:25:46","modified_gmt":"2024-10-10T07:25:46","slug":"how-to-protect-schools-from-cyberthreats","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/how-to-protect-schools-from-cyberthreats\/22288\/","title":{"rendered":"L&rsquo;\u00e9cole et les cybermenaces"},"content":{"rendered":"<p>Ces derni\u00e8res ann\u00e9es, le nombre croissant de cyberattaques visant les \u00e9tablissements scolaires est devenu une tendance tr\u00e8s inqui\u00e9tante. Aux \u00c9tats-Unis, par exemple, l\u2019enseignement scolaire est devenu l\u2019<a href=\"https:\/\/www.forbes.com\/sites\/frederickhess\/2023\/09\/20\/the-top-target-for-ransomware-its-now-k-12-schools\/?sh=549034c6563f\" target=\"_blank\" rel=\"noopener nofollow\">un des secteurs les plus cibl\u00e9s<\/a>. Selon le Commissaire \u00e0 l\u2019information (ICO) du Royaume-Uni, le nombre d\u2019attaques contre des \u00e9coles <a href=\"https:\/\/www.bbc.com\/news\/articles\/c2vwz4exq4xo\" target=\"_blank\" rel=\"noopener nofollow\">a augment\u00e9 de 55\u00a0%<\/a> entre 2022 et 2023. Un sch\u00e9ma similaire se dessine <a href=\"https:\/\/assets.sophos.com\/X24WTUEQ\/at\/j74v496cfwh4qsvgqhs4pmw\/sophos-state-of-ransomware-education-2023-wp.pdf\" target=\"_blank\" rel=\"noopener nofollow\">\u00e0 l\u2019\u00e9chelle mondiale<\/a>. Examinons la situation et les solutions que les \u00e9coles peuvent mettre en \u0153uvre pour se d\u00e9fendre.<\/p>\n<h2>Pourquoi les cybercriminels adorent les \u00e9coles<\/h2>\n<p>Plusieurs facteurs contribuent \u00e0 la vuln\u00e9rabilit\u00e9 croissante des \u00e9coles, ce qui en fait des cibles attrayantes pour les cybercriminels\u00a0:<\/p>\n<ul>\n<li><strong>Une d\u00e9pendance \u00e0 l\u2019\u00e9gard de la technologie.<\/strong> Les \u00e9tablissements scolaires adoptent rapidement les technologies num\u00e9riques et d\u00e9pendent donc de l\u2019infrastructure informatique, tant dans les salles de classe que dans les bureaux de l\u2019administration. Toutefois, leurs pratiques en mati\u00e8re de cybers\u00e9curit\u00e9 laissent souvent \u00e0 d\u00e9sirer.<\/li>\n<li><strong>Des donn\u00e9es pr\u00e9cieuses.<\/strong> Les \u00e9tablissements scolaires stockent une multitude d\u2019informations confidentielles, notamment des donn\u00e9es concernant les \u00e9l\u00e8ves et le personnel, ainsi que des dossiers financiers. Les violations de donn\u00e9es peuvent avoir des cons\u00e9quences d\u00e9vastatrices, et ces donn\u00e9es sont exactement ce que les pirates informatiques recherchent.<\/li>\n<li><strong>Des ressources rares.<\/strong> Les \u00e9coles sont souvent confront\u00e9es \u00e0 des budgets limit\u00e9s et \u00e0 une p\u00e9nurie de professionnels qualifi\u00e9s en informatique, en particulier dans le domaine de la cybers\u00e9curit\u00e9.<\/li>\n<li><strong>Une faible sensibilisation des utilisateurs.<\/strong> Un grand nombre d\u2019utilisateurs d\u2019ordinateurs dans les \u00e9coles manquent de connaissances en mati\u00e8re de cybers\u00e9curit\u00e9. Ils sont donc vuln\u00e9rables aux attaques de phishing, aux programmes malveillants et \u00e0 d\u2019autres cybermenaces. Bien souvent, les enseignants ne sont pas beaucoup plus comp\u00e9tents en la mati\u00e8re.<\/li>\n<\/ul>\n<p>Les \u00e9tablissements d\u2019enseignement se retrouvent donc dans une situation d\u00e9licate. Qui plus est, les attaques fructueuses attirent l\u2019attention du public, ce qui donne du poids aux cybercriminels, notamment lors de la n\u00e9gociation de la ran\u00e7on \u00e0 la suite d\u2019une attaque par ransomware. La nature essentielle et l\u2019importance sociale des \u00e9tablissements scolaires jouent \u00e9galement un r\u00f4le important.<\/p>\n<p>Certes, si une attaque par ransomware entra\u00eene la fermeture temporaire d\u2019une cha\u00eene de magasins, c\u2019est d\u00e9sagr\u00e9able, mais avant tout pour l\u2019entreprise elle-m\u00eame. En effet, les clients peuvent g\u00e9n\u00e9ralement aller voir ailleurs assez facilement. Cependant, si une cyberattaque interrompt l\u2019activit\u00e9 d\u2019une \u00e9cole, les cons\u00e9quences sont bien plus graves. Les \u00e9l\u00e8ves ne vont plus en cours, leurs r\u00e9sultats scolaires s\u2019en ressentent et les parents doivent organiser la garde de leurs enfants, sans compter les autres tracas qui en d\u00e9coulent.<\/p>\n<h2>Cyberattaques contre les \u00e9tablissements scolaires<\/h2>\n<p>Les attaques contre le secteur de l\u2019\u00e9ducation sont d\u00e9sormais si courantes qu\u2019il n\u2019est pas n\u00e9cessaire de chercher bien loin pour trouver des exemples d\u2019incidents, m\u00eame \u00e0 grande \u00e9chelle \u2013 il suffit de lire les derniers gros titres. Il n\u2019y a pas si longtemps, une <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/highline-public-schools-closes-schools-following-cyberattack\/\" target=\"_blank\" rel=\"noopener nofollow\">cyberattaque<\/a> a vis\u00e9 Highline Public Schools, un district scolaire de l\u2019\u00c9tat de Washington aux \u00c9tats-Unis. L\u2019incident a contraint le district \u00e0 fermer temporairement ses 34\u00a0\u00e9coles, ce qui a affect\u00e9 plus de 17\u00a0000\u00a0\u00e9l\u00e8ves. Toutes les activit\u00e9s scolaires, y compris les activit\u00e9s sportives et les r\u00e9unions, ont \u00e9t\u00e9 suspendues.<\/p>\n<p>En ao\u00fbt dernier, le minist\u00e8re de l\u2019\u00c9ducation de Singapour a annonc\u00e9 qu\u2019un pirate informatique inconnu avait <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/hacker-wipes-13-000-devices-after-breaching-classroom-management-platform\/\" target=\"_blank\" rel=\"noopener nofollow\">effac\u00e9 les donn\u00e9es de 13\u00a0000\u00a0iPad et Chromebook<\/a> dont se servaient les \u00e9l\u00e8ves dans tout le pays.<\/p>\n<p>En juin, le Toronto District School Board, qui supervise pr\u00e8s de 600\u00a0\u00e9coles dans la plus grande ville du Canada, a subi une <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/toronto-district-school-board-hit-by-a-ransomware-attack\/\" target=\"_blank\" rel=\"noopener nofollow\">attaque par ransomware<\/a>. En mai, l\u2019universit\u00e9 Western Sydney, l\u2019une des plus grandes universit\u00e9s d\u2019Australie comptant plus de 35\u00a0000\u00a0\u00e9tudiants, a <a href=\"https:\/\/www.bleepingcomputer.com\/news\/security\/western-sydney-university-data-breach-exposed-student-data\/\" target=\"_blank\" rel=\"noopener nofollow\">fait \u00e9tat d\u2019un piratage<\/a> de son infrastructure informatique.<\/p>\n<h2>Comment prot\u00e9ger les \u00e9coles des cyberattaques<\/h2>\n<p>\u00c9tant donn\u00e9 que le secteur de l\u2019\u00e9ducation est dans la ligne de mire des cybercriminels, les syst\u00e8mes informatiques des \u00e9coles ont besoin d\u2019une protection efficace.<\/p>\n<p>Alors, comment proc\u00e9der\u00a0? Alors que les grandes \u00e9coles, les lyc\u00e9es et les universit\u00e9s peuvent allouer des budgets importants \u00e0 des logiciels d\u2019entreprise et \u00e0 du personnel sp\u00e9cialis\u00e9 dans la cybers\u00e9curit\u00e9, les petites \u00e9coles ne disposent souvent pas de ces ressources.<\/p>\n<p>Par cons\u00e9quent, ces \u00e9coles ont parfois recours \u00e0 des logiciels de s\u00e9curit\u00e9 destin\u00e9s \u00e0 un usage domestique. Malheureusement, ce n\u2019est pas la solution id\u00e9ale. Comme ces produits ne sont pas con\u00e7us pour assurer une gestion centralis\u00e9e, leur d\u00e9ploiement sur de nombreux ordinateurs de l\u2019\u00e9cole, sans parler de leur gestion optimale, peut s\u2019av\u00e9rer un v\u00e9ritable casse-t\u00eate.<\/p>\n<p>Une bien meilleure solution pour les petites \u00e9coles serait un produit con\u00e7u pour les petites et moyennes entreprises (PME), comme <a href=\"https:\/\/www.kaspersky.fr\/small-business-security\/small-office-security?icid=fr_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_banner____ksos___\" target=\"_blank\" rel=\"noopener\">Kaspersky Small Office Security<\/a>. Un tel logiciel de s\u00e9curit\u00e9 offre toutes les fonctionnalit\u00e9s indispensables \u00e0 une s\u00e9curit\u00e9 de base :<\/p>\n<ul>\n<li>Protection fiable contre les ransomwares et autres programmes malveillants<\/li>\n<li>Sauvegardes automatiques<\/li>\n<li>Gestionnaire de mots de passe pour prot\u00e9ger les comptes<\/li>\n<li>Recherche de vuln\u00e9rabilit\u00e9s et bien plus encore<\/li>\n<\/ul>\n<p>En outre, <a href=\"https:\/\/www.kaspersky.fr\/small-business-security\/small-office-security?icid=fr_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_banner____ksos___\" target=\"_blank\" rel=\"noopener\">les solutions de s\u00e9curit\u00e9 pour les PME<\/a> sont faciles \u00e0 d\u00e9ployer et ne n\u00e9cessitent aucune configuration suppl\u00e9mentaire. Il n\u2019est donc pas n\u00e9cessaire de faire appel \u00e0 un sp\u00e9cialiste en informatique ou en s\u00e9curit\u00e9 pour param\u00e9trer ou g\u00e9rer la solution.<\/p>\n<p>Pour renforcer encore la cybers\u00e9curit\u00e9 des \u00e9coles, nous recommandons \u00e9galement de former le personnel afin de le sensibiliser aux cybermenaces. Cela est facile \u00e0 configurer avec notre plateforme <a href=\"https:\/\/k-asap.com\/fr\/?icid=fr_kdailyplacehold_acq_ona_smm__onl_b2b_kasperskydaily_wpplaceholder____kasap___\" target=\"_blank\" rel=\"noopener\">Kaspersky Automated Security Awareness Platform<\/a>, qui permet de r\u00e9duire \u00e0 la fois le temps et le co\u00fbt de la formation.<\/p>\n<input type=\"hidden\" class=\"category_for_banner\" value=\"ksos\">\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi la cybers\u00e9curit\u00e9 est essentielle dans le domaine de l&rsquo;\u00e9ducation et comment prot\u00e9ger les \u00e9coles contre les attaques.<\/p>\n","protected":false},"author":2706,"featured_media":22289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[2112,3150,686,7],"tags":[4504,87,3861,3548,1236,3031,4035,4503,204,4502,503,920,55,61,4482],"class_list":{"0":"post-22288","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-business","8":"category-enterprise","9":"category-threats","10":"category-products","11":"tag-atteintes-a-la-securite-des-donnees","12":"tag-conseils","13":"tag-cyberattaques","14":"tag-ecole","15":"tag-education","16":"tag-formation","17":"tag-kaspersky-automated-security-awareness-platform","18":"tag-kaspersky-small-office-security","19":"tag-menaces","20":"tag-petites-et-moyennes-entreprises","21":"tag-pme","22":"tag-programmes-malveillants","23":"tag-protection","24":"tag-securite","25":"tag-violations"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/how-to-protect-schools-from-cyberthreats\/22288\/"},{"hreflang":"en-in","url":"https:\/\/www.kaspersky.co.in\/blog\/how-to-protect-schools-from-cyberthreats\/28087\/"},{"hreflang":"en-ae","url":"https:\/\/me-en.kaspersky.com\/blog\/how-to-protect-schools-from-cyberthreats\/23348\/"},{"hreflang":"ar","url":"https:\/\/me.kaspersky.com\/blog\/how-to-protect-schools-from-cyberthreats\/12099\/"},{"hreflang":"en-gb","url":"https:\/\/www.kaspersky.co.uk\/blog\/how-to-protect-schools-from-cyberthreats\/28240\/"},{"hreflang":"es-mx","url":"https:\/\/latam.kaspersky.com\/blog\/how-to-protect-schools-from-cyberthreats\/27750\/"},{"hreflang":"es","url":"https:\/\/www.kaspersky.es\/blog\/how-to-protect-schools-from-cyberthreats\/30482\/"},{"hreflang":"it","url":"https:\/\/www.kaspersky.it\/blog\/how-to-protect-schools-from-cyberthreats\/29235\/"},{"hreflang":"tr","url":"https:\/\/www.kaspersky.com.tr\/blog\/how-to-protect-schools-from-cyberthreats\/12870\/"},{"hreflang":"x-default","url":"https:\/\/www.kaspersky.com\/blog\/how-to-protect-schools-from-cyberthreats\/52262\/"},{"hreflang":"pt-br","url":"https:\/\/www.kaspersky.com.br\/blog\/how-to-protect-schools-from-cyberthreats\/23046\/"},{"hreflang":"de","url":"https:\/\/www.kaspersky.de\/blog\/how-to-protect-schools-from-cyberthreats\/31698\/"},{"hreflang":"ja","url":"https:\/\/blog.kaspersky.co.jp\/how-to-protect-schools-from-cyberthreats\/37309\/"},{"hreflang":"en-au","url":"https:\/\/www.kaspersky.com.au\/blog\/how-to-protect-schools-from-cyberthreats\/34163\/"},{"hreflang":"en-za","url":"https:\/\/www.kaspersky.co.za\/blog\/how-to-protect-schools-from-cyberthreats\/33817\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/education\/","name":"\u00e9ducation"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/22288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/2706"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=22288"}],"version-history":[{"count":3,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/22288\/revisions"}],"predecessor-version":[{"id":22292,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/22288\/revisions\/22292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/22289"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=22288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=22288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=22288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}