{"id":862,"date":"2013-04-23T14:14:54","date_gmt":"2013-04-23T14:14:54","guid":{"rendered":"http:\/\/kasperskydaily.com\/france\/?p=862"},"modified":"2020-02-26T15:39:23","modified_gmt":"2020-02-26T15:39:23","slug":"les-navigateurs-internet-alternatifs","status":"publish","type":"post","link":"https:\/\/www.kaspersky.fr\/blog\/les-navigateurs-internet-alternatifs\/862\/","title":{"rendered":"Les navigateurs Internet alternatifs"},"content":{"rendered":"<p>Internet Explorer, <a href=\"https:\/\/www.kaspersky.fr\/blog\/la-securite-sur-le-navigateur-google-chrome\/\" target=\"_blank\" rel=\"noopener\">Google Chrome<\/a>, Safari et <a href=\"https:\/\/www.kaspersky.fr\/blog\/caracteristiques-de-securite-dun-navigateur-internet-mozilla-firefox\/\" target=\"_blank\" rel=\"noopener\">Mozilla Firefox<\/a> sont tous des navigateurs Web modernes et fonctionnels. Ils offrent tous une importante s\u00e9rie de caract\u00e9ristiques, d\u2019extensions et de plug-ins int\u00e9ressants et tous sont dot\u00e9s de param\u00e8tres compl\u00e8tement personnalisables afin de r\u00e9pondre aux besoins d\u2019une grande majorit\u00e9 d\u2019utilisateurs. Malheureusement, rien n\u2019est gratuit, et les quatre grands navigateurs sont, par nature, des outils utilis\u00e9s respectivement par Microsoft, Google, Apple et Mozilla, pour surveiller leurs utilisateurs en ligne et vendre leurs donn\u00e9es de navigation aux grosses compagnies de courtage en donn\u00e9es. Presque tous les param\u00e8tres permettant le pistage sont d\u00e9sactiv\u00e9s par d\u00e9faut et doivent \u00eatre trouv\u00e9s et mis en place par des utilisateurs soucieux de leur confidentialit\u00e9.<\/p>\n<p><a href=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06104135\/browsers_blog_title_FR.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-863\" alt=\"navigateurs_alternatifs\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06104135\/browsers_blog_title_FR.png\" width=\"640\" height=\"420\"><\/a><\/p>\n<p>Heureusement, il existe un grand nombre de navigateurs alternatifs en ligne, et il en existe chaque jour de plus en plus. Nombreux de ces navigateurs sont con\u00e7us dans l\u2019id\u00e9e de r\u00e9volutionner la navigation Internet, mais d\u2019autres sont \u00e9galement con\u00e7us dans le but de mieux prot\u00e9ger la vie priv\u00e9e des utilisateurs ainsi que leur s\u00e9curit\u00e9 et c\u2019est \u00e0 ses navigateurs que nous nous int\u00e9ressons.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06093218\/zipzaplogo-300x84.png\" width=\"300\" height=\"84\">Le <a href=\"http:\/\/zipzaphome.com\/zipzap\/cgi-bin\/zzdownload.cgi\" target=\"_blank\" rel=\"noopener nofollow\">navigateur ZipZap<\/a> fait partie de notre liste car il essaie d\u2019occuper une niche bien particuli\u00e8re \u2013 celle des navigateurs adapt\u00e9s \u00e0 toute la famille. Il n\u2019offre peut-\u00eatre pas par d\u00e9faut, l\u2019exp\u00e9rience de navigation la plus s\u00e9curis\u00e9e, mais il donne aux parents la possibilit\u00e9 d\u2019obtenir un certain contr\u00f4le sur les activit\u00e9s en ligne de leurs enfants. Avec ZipZap, chaque membre de la famille obtient son propre compte de navigation sur lequel l\u2019administrateur principal (maman et\/ou papa) pourra mettre en place un certain nombre de contr\u00f4les, parmi eux : la possibilit\u00e9 d\u2019\u00e9tablir des filtres pr\u00e9-install\u00e9s qui emp\u00eachent l\u2019acc\u00e8s \u00e0 un certain nombre de cat\u00e9gories de contenu en ligne inappropri\u00e9 ou peut-\u00eatre juste un peu trop distrayant, de cr\u00e9er des listes d\u2019amis avec lesquels vos enfants seront autoris\u00e9s \u00e0 communiquer automatiquement (quand vous les y autorisez), et de permettre qu\u2019ils acc\u00e8dent facilement \u00e0 des sites adapt\u00e9s \u00e0 leur \u00e2ge.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06093218\/comodo-browser.png\" width=\"210\" height=\"95\">Plus connus pour leur travail comme experts en mati\u00e8re de certificats num\u00e9riques*, ou peut-\u00eatre pour un incident survenu en Mars 2011 dans lequel <a href=\"https:\/\/threatpost.com\/en_us\/blogs\/phony-ssl-certificates-issued-google-yahoo-skype-others-032311\" target=\"_blank\" rel=\"noopener nofollow\">les hackers ont r\u00e9ussi \u00e0 compromettre leur certificat<\/a>, le navigateur Internet, <a href=\"http:\/\/www.comodo.com\/home\/browsers-toolbars\/browser.php\" target=\"_blank\" rel=\"noopener nofollow\">Comodo Dragon<\/a>, se d\u00e9finit comme un navigateur soucieux de notre s\u00e9curit\u00e9. Comme ZipZap, Comodo Dragon est bas\u00e9 sur le code source du navigateur \u00e0 source ouverte de Google, Chromium. Le navigateur Dragon est dot\u00e9 de param\u00e8tres de confidentialit\u00e9 allant au-del\u00e0 de ceux mis en place dans Chromium comprenant, par exemple, une technologie de validation des domaines qui favorise les certificats les plus fiables plut\u00f4t que ceux qui le sont moins et qui emp\u00eache les cookies, les logiciels espions, et toutes autres formes de pistage.<\/p>\n<p><a href=\"http:\/\/dooble.sourceforge.net\/\" target=\"_blank\" rel=\"noopener nofollow\">Dooble est un autre navigateur qui affirme avoir pour but la protection de la vie priv\u00e9e<\/a> des utilisateurs. Ce dernier est disponible sur Linux, Mac et Windows. Il offre \u00e0 ses utilisateurs un syst\u00e8me de gestion et de suppression des cookies, qui peut \u00eatre r\u00e9gl\u00e9 de fa\u00e7on \u00e0 automatiquement supprimer les cookies en temps opportun. Dooble chiffre \u00e9galement les informations de l\u2019utilisateur et leur donne plus de contr\u00f4le sur les contenus provenant de tiers non-d\u00e9sir\u00e9s ou potentiellement dangereux.<\/p>\n<p><a href=\"http:\/\/www.omnigroup.com\/products\/omniweb\/\" target=\"_blank\" rel=\"noopener nofollow\">OmniWeb<\/a> est une alternative au navigateur d\u2019Apple, Safari, pour les Mac. Il a attir\u00e9 notre attention car en plus du blocage des publicit\u00e9s habituel, il permet aux utilisateurs de bloquer tout contenu provenant de serveurs de publicit\u00e9 connus. OmniWeb permet \u00e9galement aux utilisateurs de bloquer les contenus n\u00e9cessitant Flash, ce qui est plut\u00f4t int\u00e9ressant car Adobe Flash Player est, tout comme Java, une des plateformes les plus touch\u00e9es par les probl\u00e8mes de s\u00e9curit\u00e9.<\/p>\n<p><a href=\"http:\/\/caminobrowser.org\/features\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06093217\/camino.png\" width=\"314\" height=\"126\">Camino<\/a> est une autre alternative \u00e0 Safari, mais ses cr\u00e9ateurs semblent l\u00e9g\u00e8rement plus int\u00e9ress\u00e9s par ses param\u00e8tres de s\u00e9curit\u00e9. Le navigateur Camino offre les m\u00eames param\u00e8tres de protection par d\u00e9faut contre l\u2019hame\u00e7onnage et les malwares que Safari, Chrome et Firefox. Il poss\u00e8de \u00e9galement un param\u00e8tre de \u00ab\u00a0blocage des nuisances\u00a0\u00bb qui bloque les pop-ups et les animations Flash automatiques. Les utilisateurs qui souhaitent que Flash fonctionne automatiquement sur certains sites peuvent ajouter une exception afin d\u2019autoriser Flash ou m\u00eame les pop-ups sur certains sites Web en particulier.<\/p>\n<p><a href=\"http:\/\/www.srware.net\/en\/software_srware_iron.php\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06093217\/srware.png\" width=\"232\" height=\"127\">SRWare Iron<\/a> est un autre navigateur qui se base sur le navigateur Chromium et qui se pr\u00e9sente comme le navigateur Chrome\u00a0 sans les nombreux param\u00e8tres de Google qui violent votre vie priv\u00e9e, tels que les suggestions de recherche, les rapports d\u2019erreur, le pistage des URL et autres param\u00e8tres requis par Google afin de pister le comportement de leurs utilisateurs en ligne. SRWare Iron contient \u00e9galement un bloqueur de publicit\u00e9 par d\u00e9faut qui n\u2019est pas activ\u00e9 dans la version standard de Chrome.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" alt=\"\" src=\"https:\/\/media.kasperskydaily.com\/wp-content\/uploads\/sites\/93\/2013\/04\/06093217\/duckduckgo.png\" width=\"265\" height=\"220\">Le moteur de recherche alternatif, <a href=\"https:\/\/duckduckgo.com\/\" target=\"_blank\" rel=\"noopener nofollow\">DuckDuckGo<\/a>, m\u00e9rite \u00e9galement d\u2019\u00eatre mentionn\u00e9. Bien qu\u2019il ne s\u2019agisse pas d\u2019un navigateur complet, il offre de solides r\u00e9sultats de recherche sans pister le comportement des utilisateurs et il ne d\u00e9ploie pas de filtre bulle bas\u00e9 sur le comportement des utilisateurs. En d\u2019autres termes, contrairement \u00e0 la recherche sur Google o\u00f9 les m\u00eames recherches g\u00e9n\u00e8rent des r\u00e9sultats diff\u00e9rents suivant les utilisateurs, les recherches identiques sur DuckDuckGo g\u00e9n\u00e8reront toujours les m\u00eames r\u00e9sultats sans aucune influence du comportement des utilisateurs.<\/p>\n<p><em>*Les certificats num\u00e9riques sont des signatures en ligne associ\u00e9es au trafic de navigation Internet et aux t\u00e9l\u00e9chargements. Le syst\u00e8me de certificats num\u00e9riques se base premi\u00e8rement sur une relation de confiance entre l\u2019utilisateur et le vendeur : de fa\u00e7on tr\u00e8s simplifi\u00e9e, il existe afin d\u2019assurer que l\u2019origine des t\u00e9l\u00e9chargements est bien celle indiqu\u00e9e, et que le trafic sortant va l\u00e0 o\u00f9 il est suppos\u00e9 aller.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet Explorer, Google Chrome, Safari et Mozilla Firefox sont tous des navigateurs Web modernes et fonctionnels. Ils offrent tous une importante s\u00e9rie de caract\u00e9ristiques, d\u2019extensions et de plug-ins int\u00e9ressants et<\/p>\n","protected":false},"author":42,"featured_media":864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[81,61],"class_list":{"0":"post-862","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"tag-navigateur","9":"tag-securite"},"hreflang":[{"hreflang":"fr","url":"https:\/\/www.kaspersky.fr\/blog\/les-navigateurs-internet-alternatifs\/862\/"}],"acf":[],"banners":"","maintag":{"url":"https:\/\/www.kaspersky.fr\/blog\/tag\/navigateur\/","name":"navigateur"},"_links":{"self":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":2,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/862\/revisions"}],"predecessor-version":[{"id":13871,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/posts\/862\/revisions\/13871"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media\/864"}],"wp:attachment":[{"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/media?parent=862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/categories?post=862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kaspersky.fr\/blog\/wp-json\/wp\/v2\/tags?post=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}